{"id":18853,"date":"2018-09-01T00:00:00","date_gmt":"2018-08-31T22:00:00","guid":{"rendered":"http:\/\/igr.preprod.e-declic.net\/visite-de-christopher-chan-a-ligr-iae-rennes\/"},"modified":"2018-09-01T00:00:00","modified_gmt":"2018-08-31T22:00:00","slug":"visite-de-christopher-chan-a-ligr-iae-rennes","status":"publish","type":"post","link":"https:\/\/www.igr.univ-rennes.fr\/fr\/visite-de-christopher-chan-a-ligr-iae-rennes\/","title":{"rendered":"Visite de Christopher CHAN \u00e0 l&rsquo;IGR-IAE Rennes"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":3279,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[68],"tags":[],"class_list":["post-18853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-international"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visite de Christopher CHAN \u00e0 l&#039;IGR-IAE Rennes - IGR IAE Rennes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.igr.univ-rennes.fr\/fr\/visite-de-christopher-chan-a-ligr-iae-rennes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visite de Christopher CHAN \u00e0 l&#039;IGR-IAE Rennes - IGR IAE Rennes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.igr.univ-rennes.fr\/fr\/visite-de-christopher-chan-a-ligr-iae-rennes\/\" \/>\n<meta property=\"og:site_name\" content=\"IGR IAE Rennes\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-31T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.igr.univ-rennes.fr\/wp-content\/uploads\/2019\/12\/york-university-site.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"606\" \/>\n\t<meta property=\"og:image:height\" content=\"407\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mmorvant\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"mmorvant\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/visite-de-christopher-chan-a-ligr-iae-rennes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/visite-de-christopher-chan-a-ligr-iae-rennes\\\/\"},\"author\":{\"name\":\"mmorvant\",\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/#\\\/schema\\\/person\\\/04158ffe391a6d520da5123006c155ab\"},\"headline\":\"Visite de Christopher CHAN \u00e0 l&rsquo;IGR-IAE Rennes\",\"datePublished\":\"2018-08-31T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/visite-de-christopher-chan-a-ligr-iae-rennes\\\/\"},\"wordCount\":7,\"publisher\":{\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/visite-de-christopher-chan-a-ligr-iae-rennes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/york-university-site.jpg\",\"articleSection\":[\"International\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/visite-de-christopher-chan-a-ligr-iae-rennes\\\/\",\"url\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/visite-de-christopher-chan-a-ligr-iae-rennes\\\/\",\"name\":\"Visite de Christopher CHAN \u00e0 l'IGR-IAE Rennes - IGR IAE Rennes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/visite-de-christopher-chan-a-ligr-iae-rennes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/visite-de-christopher-chan-a-ligr-iae-rennes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/york-university-site.jpg\",\"datePublished\":\"2018-08-31T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/visite-de-christopher-chan-a-ligr-iae-rennes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/visite-de-christopher-chan-a-ligr-iae-rennes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/visite-de-christopher-chan-a-ligr-iae-rennes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/york-university-site.jpg\",\"contentUrl\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/york-university-site.jpg\",\"width\":606,\"height\":407,\"caption\":\"york university\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/visite-de-christopher-chan-a-ligr-iae-rennes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visite de Christopher CHAN \u00e0 l&rsquo;IGR-IAE Rennes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/\",\"name\":\"IGR IAE Rennes\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/#organization\",\"name\":\"IGR IAE Rennes\",\"url\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Logo-IGR-IAE-Rennes_Blanc-300dpi-RVB-e1597327228224.png\",\"contentUrl\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Logo-IGR-IAE-Rennes_Blanc-300dpi-RVB-e1597327228224.png\",\"width\":290,\"height\":107,\"caption\":\"IGR IAE Rennes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.igr.univ-rennes.fr\\\/fr\\\/#\\\/schema\\\/person\\\/04158ffe391a6d520da5123006c155ab\",\"name\":\"mmorvant\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/448d30b6495f9407002e346fc6b3709116e8a191ce8a33d0441d7e3d4fa42b6b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/448d30b6495f9407002e346fc6b3709116e8a191ce8a33d0441d7e3d4fa42b6b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/448d30b6495f9407002e346fc6b3709116e8a191ce8a33d0441d7e3d4fa42b6b?s=96&d=mm&r=g\",\"caption\":\"mmorvant\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visite de Christopher CHAN \u00e0 l'IGR-IAE Rennes - IGR IAE Rennes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.igr.univ-rennes.fr\/fr\/visite-de-christopher-chan-a-ligr-iae-rennes\/","og_locale":"fr_FR","og_type":"article","og_title":"Visite de Christopher CHAN \u00e0 l'IGR-IAE Rennes - IGR IAE Rennes","og_url":"https:\/\/www.igr.univ-rennes.fr\/fr\/visite-de-christopher-chan-a-ligr-iae-rennes\/","og_site_name":"IGR IAE Rennes","article_published_time":"2018-08-31T22:00:00+00:00","og_image":[{"width":606,"height":407,"url":"https:\/\/www.igr.univ-rennes.fr\/wp-content\/uploads\/2019\/12\/york-university-site.jpg","type":"image\/jpeg"}],"author":"mmorvant","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"mmorvant"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/visite-de-christopher-chan-a-ligr-iae-rennes\/#article","isPartOf":{"@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/visite-de-christopher-chan-a-ligr-iae-rennes\/"},"author":{"name":"mmorvant","@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/#\/schema\/person\/04158ffe391a6d520da5123006c155ab"},"headline":"Visite de Christopher CHAN \u00e0 l&rsquo;IGR-IAE Rennes","datePublished":"2018-08-31T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/visite-de-christopher-chan-a-ligr-iae-rennes\/"},"wordCount":7,"publisher":{"@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/#organization"},"image":{"@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/visite-de-christopher-chan-a-ligr-iae-rennes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.igr.univ-rennes.fr\/wp-content\/uploads\/2019\/12\/york-university-site.jpg","articleSection":["International"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/visite-de-christopher-chan-a-ligr-iae-rennes\/","url":"https:\/\/www.igr.univ-rennes.fr\/fr\/visite-de-christopher-chan-a-ligr-iae-rennes\/","name":"Visite de Christopher CHAN \u00e0 l'IGR-IAE Rennes - IGR IAE Rennes","isPartOf":{"@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/visite-de-christopher-chan-a-ligr-iae-rennes\/#primaryimage"},"image":{"@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/visite-de-christopher-chan-a-ligr-iae-rennes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.igr.univ-rennes.fr\/wp-content\/uploads\/2019\/12\/york-university-site.jpg","datePublished":"2018-08-31T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/visite-de-christopher-chan-a-ligr-iae-rennes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.igr.univ-rennes.fr\/fr\/visite-de-christopher-chan-a-ligr-iae-rennes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/visite-de-christopher-chan-a-ligr-iae-rennes\/#primaryimage","url":"https:\/\/www.igr.univ-rennes.fr\/wp-content\/uploads\/2019\/12\/york-university-site.jpg","contentUrl":"https:\/\/www.igr.univ-rennes.fr\/wp-content\/uploads\/2019\/12\/york-university-site.jpg","width":606,"height":407,"caption":"york university"},{"@type":"BreadcrumbList","@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/visite-de-christopher-chan-a-ligr-iae-rennes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.igr.univ-rennes.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Visite de Christopher CHAN \u00e0 l&rsquo;IGR-IAE Rennes"}]},{"@type":"WebSite","@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/#website","url":"https:\/\/www.igr.univ-rennes.fr\/fr\/","name":"IGR IAE Rennes","description":"","publisher":{"@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.igr.univ-rennes.fr\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/#organization","name":"IGR IAE Rennes","url":"https:\/\/www.igr.univ-rennes.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.igr.univ-rennes.fr\/wp-content\/uploads\/2020\/06\/Logo-IGR-IAE-Rennes_Blanc-300dpi-RVB-e1597327228224.png","contentUrl":"https:\/\/www.igr.univ-rennes.fr\/wp-content\/uploads\/2020\/06\/Logo-IGR-IAE-Rennes_Blanc-300dpi-RVB-e1597327228224.png","width":290,"height":107,"caption":"IGR IAE Rennes"},"image":{"@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.igr.univ-rennes.fr\/fr\/#\/schema\/person\/04158ffe391a6d520da5123006c155ab","name":"mmorvant","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/448d30b6495f9407002e346fc6b3709116e8a191ce8a33d0441d7e3d4fa42b6b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/448d30b6495f9407002e346fc6b3709116e8a191ce8a33d0441d7e3d4fa42b6b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/448d30b6495f9407002e346fc6b3709116e8a191ce8a33d0441d7e3d4fa42b6b?s=96&d=mm&r=g","caption":"mmorvant"}}]}},"_links":{"self":[{"href":"https:\/\/www.igr.univ-rennes.fr\/fr\/wp-json\/wp\/v2\/posts\/18853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.igr.univ-rennes.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.igr.univ-rennes.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.igr.univ-rennes.fr\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.igr.univ-rennes.fr\/fr\/wp-json\/wp\/v2\/comments?post=18853"}],"version-history":[{"count":0,"href":"https:\/\/www.igr.univ-rennes.fr\/fr\/wp-json\/wp\/v2\/posts\/18853\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.igr.univ-rennes.fr\/fr\/wp-json\/wp\/v2\/media\/3279"}],"wp:attachment":[{"href":"https:\/\/www.igr.univ-rennes.fr\/fr\/wp-json\/wp\/v2\/media?parent=18853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.igr.univ-rennes.fr\/fr\/wp-json\/wp\/v2\/categories?post=18853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.igr.univ-rennes.fr\/fr\/wp-json\/wp\/v2\/tags?post=18853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}